{"id":13108,"date":"2019-02-20T12:46:17","date_gmt":"2019-02-20T12:46:17","guid":{"rendered":"https:\/\/luxwatch.it\/orologi\/senza%20categoria\/blancpain-villeret-6102-3642-55a\/"},"modified":"2023-11-10T11:21:14","modified_gmt":"2023-11-10T10:21:14","slug":"blancpain-villeret-6102-3642-55a","status":"publish","type":"product","link":"https:\/\/luxwatch.it\/orologi\/blancpain\/blancpain-villeret-6102-3642-55a\/","title":{"rendered":"Blancpain Villeret Ultra Thin"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":13971,"template":"","meta":{"pmpro_default_level":0},"product_cat":[748,749],"product_tag":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v16.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Blancpain Villeret Ultra Thin 6102-3642-55A Oro rosa Acquisto Prezzo Migliore - Luxwatch.it<\/title>\n<meta name=\"description\" content=\"Scopri l&#039;orologio Blancpain Villeret Ultra Thin 6102-3642-55A, con scheda dettagliata, prezzo e dove acquistarlo a un prezzo speciale.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/luxwatch.it\/orologi\/blancpain\/blancpain-villeret-6102-3642-55a\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Blancpain Villeret Ultra Thin 6102-3642-55A Oro rosa Acquisto Prezzo Migliore - Luxwatch.it\" \/>\n<meta property=\"og:description\" content=\"Scopri l&#039;orologio Blancpain Villeret Ultra Thin 6102-3642-55A, con scheda dettagliata, prezzo e dove acquistarlo a un prezzo speciale.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/luxwatch.it\/orologi\/blancpain\/blancpain-villeret-6102-3642-55a\/\" \/>\n<meta property=\"og:site_name\" content=\"Luxwatch.it\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-10T10:21:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/luxwatch.it\/orologi\/wp-content\/uploads\/2019\/02\/6102-3642-55A-Blancpain-Villeret.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"396\" \/>\n\t<meta property=\"og:image:height\" content=\"560\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/luxwatch.it\/orologi\/#website\",\"url\":\"https:\/\/luxwatch.it\/orologi\/\",\"name\":\"Luxwatch.it\",\"description\":\"orologi di lusso\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/luxwatch.it\/orologi\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/luxwatch.it\/orologi\/blancpain\/blancpain-villeret-6102-3642-55a\/#primaryimage\",\"inLanguage\":\"it-IT\",\"url\":\"https:\/\/luxwatch.it\/orologi\/wp-content\/uploads\/2019\/02\/6102-3642-55A-Blancpain-Villeret.jpg\",\"contentUrl\":\"https:\/\/luxwatch.it\/orologi\/wp-content\/uploads\/2019\/02\/6102-3642-55A-Blancpain-Villeret.jpg\",\"width\":396,\"height\":560,\"caption\":\"6102-3642-55A Blancpain Villeret Ultra Thin\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/luxwatch.it\/orologi\/blancpain\/blancpain-villeret-6102-3642-55a\/#webpage\",\"url\":\"https:\/\/luxwatch.it\/orologi\/blancpain\/blancpain-villeret-6102-3642-55a\/\",\"name\":\"Blancpain Villeret Ultra Thin 6102-3642-55A Oro rosa Acquisto Prezzo Migliore - Luxwatch.it\",\"isPartOf\":{\"@id\":\"https:\/\/luxwatch.it\/orologi\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/luxwatch.it\/orologi\/blancpain\/blancpain-villeret-6102-3642-55a\/#primaryimage\"},\"datePublished\":\"2019-02-20T12:46:17+00:00\",\"dateModified\":\"2023-11-10T10:21:14+00:00\",\"description\":\"Scopri l'orologio Blancpain Villeret Ultra Thin 6102-3642-55A, con scheda dettagliata, prezzo e dove acquistarlo a un prezzo speciale.\",\"breadcrumb\":{\"@id\":\"https:\/\/luxwatch.it\/orologi\/blancpain\/blancpain-villeret-6102-3642-55a\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/luxwatch.it\/orologi\/blancpain\/blancpain-villeret-6102-3642-55a\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/luxwatch.it\/orologi\/blancpain\/blancpain-villeret-6102-3642-55a\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/luxwatch.it\/orologi\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Trova il tuo orologio preferito al miglior prezzo.\",\"item\":\"https:\/\/luxwatch.it\/orologi\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Blancpain Villeret Ultra Thin\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Blancpain Villeret Ultra Thin 6102-3642-55A Oro rosa Acquisto Prezzo Migliore - Luxwatch.it","description":"Scopri l'orologio Blancpain Villeret Ultra Thin 6102-3642-55A, con scheda dettagliata, prezzo e dove acquistarlo a un prezzo speciale.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/luxwatch.it\/orologi\/blancpain\/blancpain-villeret-6102-3642-55a\/","og_locale":"it_IT","og_type":"article","og_title":"Blancpain Villeret Ultra Thin 6102-3642-55A Oro rosa Acquisto Prezzo Migliore - Luxwatch.it","og_description":"Scopri l'orologio Blancpain Villeret Ultra Thin 6102-3642-55A, con scheda dettagliata, prezzo e dove acquistarlo a un prezzo speciale.","og_url":"https:\/\/luxwatch.it\/orologi\/blancpain\/blancpain-villeret-6102-3642-55a\/","og_site_name":"Luxwatch.it","article_modified_time":"2023-11-10T10:21:14+00:00","og_image":[{"width":396,"height":560,"url":"https:\/\/luxwatch.it\/orologi\/wp-content\/uploads\/2019\/02\/6102-3642-55A-Blancpain-Villeret.jpg","path":"\/var\/www\/luxwatch.it\/htdocs\/orologi\/wp-content\/uploads\/2019\/02\/6102-3642-55A-Blancpain-Villeret.jpg","size":"full","id":13971,"alt":"6102-3642-55A Blancpain Villeret Ultra Thin","pixels":221760,"type":"image\/jpeg"}],"twitter_card":"summary","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/luxwatch.it\/orologi\/#website","url":"https:\/\/luxwatch.it\/orologi\/","name":"Luxwatch.it","description":"orologi di lusso","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/luxwatch.it\/orologi\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"ImageObject","@id":"https:\/\/luxwatch.it\/orologi\/blancpain\/blancpain-villeret-6102-3642-55a\/#primaryimage","inLanguage":"it-IT","url":"https:\/\/luxwatch.it\/orologi\/wp-content\/uploads\/2019\/02\/6102-3642-55A-Blancpain-Villeret.jpg","contentUrl":"https:\/\/luxwatch.it\/orologi\/wp-content\/uploads\/2019\/02\/6102-3642-55A-Blancpain-Villeret.jpg","width":396,"height":560,"caption":"6102-3642-55A Blancpain Villeret Ultra Thin"},{"@type":"WebPage","@id":"https:\/\/luxwatch.it\/orologi\/blancpain\/blancpain-villeret-6102-3642-55a\/#webpage","url":"https:\/\/luxwatch.it\/orologi\/blancpain\/blancpain-villeret-6102-3642-55a\/","name":"Blancpain Villeret Ultra Thin 6102-3642-55A Oro rosa Acquisto Prezzo Migliore - Luxwatch.it","isPartOf":{"@id":"https:\/\/luxwatch.it\/orologi\/#website"},"primaryImageOfPage":{"@id":"https:\/\/luxwatch.it\/orologi\/blancpain\/blancpain-villeret-6102-3642-55a\/#primaryimage"},"datePublished":"2019-02-20T12:46:17+00:00","dateModified":"2023-11-10T10:21:14+00:00","description":"Scopri l'orologio Blancpain Villeret Ultra Thin 6102-3642-55A, con scheda dettagliata, prezzo e dove acquistarlo a un prezzo speciale.","breadcrumb":{"@id":"https:\/\/luxwatch.it\/orologi\/blancpain\/blancpain-villeret-6102-3642-55a\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/luxwatch.it\/orologi\/blancpain\/blancpain-villeret-6102-3642-55a\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/luxwatch.it\/orologi\/blancpain\/blancpain-villeret-6102-3642-55a\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/luxwatch.it\/orologi\/"},{"@type":"ListItem","position":2,"name":"Trova il tuo orologio preferito al miglior prezzo.","item":"https:\/\/luxwatch.it\/orologi\/"},{"@type":"ListItem","position":3,"name":"Blancpain Villeret Ultra Thin"}]}]}},"_links":{"self":[{"href":"https:\/\/luxwatch.it\/orologi\/wp-json\/wp\/v2\/product\/13108"}],"collection":[{"href":"https:\/\/luxwatch.it\/orologi\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/luxwatch.it\/orologi\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/luxwatch.it\/orologi\/wp-json\/wp\/v2\/media\/13971"}],"wp:attachment":[{"href":"https:\/\/luxwatch.it\/orologi\/wp-json\/wp\/v2\/media?parent=13108"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/luxwatch.it\/orologi\/wp-json\/wp\/v2\/product_cat?post=13108"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/luxwatch.it\/orologi\/wp-json\/wp\/v2\/product_tag?post=13108"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}