{"id":13212,"date":"2019-02-20T12:46:55","date_gmt":"2019-02-20T12:46:55","guid":{"rendered":"https:\/\/luxwatch.it\/orologi\/senza%20categoria\/franck-muller-cintr-7500scatdtfocolcrdltd5n-blc\/"},"modified":"2023-11-10T11:29:05","modified_gmt":"2023-11-10T10:29:05","slug":"franck-muller-cintr-7500scatdtfocolcrdltd5n-blc","status":"publish","type":"product","link":"https:\/\/luxwatch.it\/orologi\/franck-muller\/franck-muller-cintr-7500scatdtfocolcrdltd5n-blc\/","title":{"rendered":"Franck Muller Cintr\u00e9e Curvex Swiss Lim. Edition"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":14023,"template":"","meta":{"pmpro_default_level":0},"product_cat":[818,891],"product_tag":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v16.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Franck Muller Cintr\u00e9e Curvex Swiss Lim. Edition 7500SCATDTFOCOLCRDLTD5N-BLC Oro rosa Acquisto Prezzo Migliore - Luxwatch.it<\/title>\n<meta name=\"description\" content=\"Scopri l&#039;orologio Franck Muller Cintr\u00e9e Curvex Swiss Lim. Edition 7500SCATDTFOCOLCRDLTD5N-BLC, con scheda dettagliata, prezzo e dove acquistarlo a un prezzo speciale.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/luxwatch.it\/orologi\/franck-muller\/franck-muller-cintr-7500scatdtfocolcrdltd5n-blc\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Franck Muller Cintr\u00e9e Curvex Swiss Lim. Edition 7500SCATDTFOCOLCRDLTD5N-BLC Oro rosa Acquisto Prezzo Migliore - Luxwatch.it\" \/>\n<meta property=\"og:description\" content=\"Scopri l&#039;orologio Franck Muller Cintr\u00e9e Curvex Swiss Lim. Edition 7500SCATDTFOCOLCRDLTD5N-BLC, con scheda dettagliata, prezzo e dove acquistarlo a un prezzo speciale.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/luxwatch.it\/orologi\/franck-muller\/franck-muller-cintr-7500scatdtfocolcrdltd5n-blc\/\" \/>\n<meta property=\"og:site_name\" content=\"Luxwatch.it\" \/>\n<meta property=\"article:modified_time\" content=\"2023-11-10T10:29:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/luxwatch.it\/orologi\/wp-content\/uploads\/2019\/02\/7500SCATDTFOCOLCRDLTD5N-BLC-Franck-Muller-Cintr.png\" \/>\n\t<meta property=\"og:image:width\" content=\"373\" \/>\n\t<meta property=\"og:image:height\" content=\"560\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/luxwatch.it\/orologi\/#website\",\"url\":\"https:\/\/luxwatch.it\/orologi\/\",\"name\":\"Luxwatch.it\",\"description\":\"orologi di lusso\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/luxwatch.it\/orologi\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/luxwatch.it\/orologi\/franck-muller\/franck-muller-cintr-7500scatdtfocolcrdltd5n-blc\/#primaryimage\",\"inLanguage\":\"it-IT\",\"url\":\"https:\/\/luxwatch.it\/orologi\/wp-content\/uploads\/2019\/02\/7500SCATDTFOCOLCRDLTD5N-BLC-Franck-Muller-Cintr.png\",\"contentUrl\":\"https:\/\/luxwatch.it\/orologi\/wp-content\/uploads\/2019\/02\/7500SCATDTFOCOLCRDLTD5N-BLC-Franck-Muller-Cintr.png\",\"width\":373,\"height\":560,\"caption\":\"7500SCATDTFOCOLCRDLTD5N-BLC Franck Muller Cintr Swiss Lim. Edition\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/luxwatch.it\/orologi\/franck-muller\/franck-muller-cintr-7500scatdtfocolcrdltd5n-blc\/#webpage\",\"url\":\"https:\/\/luxwatch.it\/orologi\/franck-muller\/franck-muller-cintr-7500scatdtfocolcrdltd5n-blc\/\",\"name\":\"Franck Muller Cintr\\u00e9e Curvex Swiss Lim. Edition 7500SCATDTFOCOLCRDLTD5N-BLC Oro rosa Acquisto Prezzo Migliore - Luxwatch.it\",\"isPartOf\":{\"@id\":\"https:\/\/luxwatch.it\/orologi\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/luxwatch.it\/orologi\/franck-muller\/franck-muller-cintr-7500scatdtfocolcrdltd5n-blc\/#primaryimage\"},\"datePublished\":\"2019-02-20T12:46:55+00:00\",\"dateModified\":\"2023-11-10T10:29:05+00:00\",\"description\":\"Scopri l'orologio Franck Muller Cintr\\u00e9e Curvex Swiss Lim. Edition 7500SCATDTFOCOLCRDLTD5N-BLC, con scheda dettagliata, prezzo e dove acquistarlo a un prezzo speciale.\",\"breadcrumb\":{\"@id\":\"https:\/\/luxwatch.it\/orologi\/franck-muller\/franck-muller-cintr-7500scatdtfocolcrdltd5n-blc\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/luxwatch.it\/orologi\/franck-muller\/franck-muller-cintr-7500scatdtfocolcrdltd5n-blc\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/luxwatch.it\/orologi\/franck-muller\/franck-muller-cintr-7500scatdtfocolcrdltd5n-blc\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/luxwatch.it\/orologi\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Trova il tuo orologio preferito al miglior prezzo.\",\"item\":\"https:\/\/luxwatch.it\/orologi\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Franck Muller Cintr\\u00e9e Curvex Swiss Lim. Edition\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Franck Muller Cintr\u00e9e Curvex Swiss Lim. Edition 7500SCATDTFOCOLCRDLTD5N-BLC Oro rosa Acquisto Prezzo Migliore - Luxwatch.it","description":"Scopri l'orologio Franck Muller Cintr\u00e9e Curvex Swiss Lim. Edition 7500SCATDTFOCOLCRDLTD5N-BLC, con scheda dettagliata, prezzo e dove acquistarlo a un prezzo speciale.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/luxwatch.it\/orologi\/franck-muller\/franck-muller-cintr-7500scatdtfocolcrdltd5n-blc\/","og_locale":"it_IT","og_type":"article","og_title":"Franck Muller Cintr\u00e9e Curvex Swiss Lim. Edition 7500SCATDTFOCOLCRDLTD5N-BLC Oro rosa Acquisto Prezzo Migliore - Luxwatch.it","og_description":"Scopri l'orologio Franck Muller Cintr\u00e9e Curvex Swiss Lim. Edition 7500SCATDTFOCOLCRDLTD5N-BLC, con scheda dettagliata, prezzo e dove acquistarlo a un prezzo speciale.","og_url":"https:\/\/luxwatch.it\/orologi\/franck-muller\/franck-muller-cintr-7500scatdtfocolcrdltd5n-blc\/","og_site_name":"Luxwatch.it","article_modified_time":"2023-11-10T10:29:05+00:00","og_image":[{"width":373,"height":560,"url":"https:\/\/luxwatch.it\/orologi\/wp-content\/uploads\/2019\/02\/7500SCATDTFOCOLCRDLTD5N-BLC-Franck-Muller-Cintr.png","path":"\/var\/www\/luxwatch.it\/htdocs\/orologi\/wp-content\/uploads\/2019\/02\/7500SCATDTFOCOLCRDLTD5N-BLC-Franck-Muller-Cintr.png","size":"full","id":14023,"alt":"7500SCATDTFOCOLCRDLTD5N-BLC Franck Muller Cintr Swiss Lim. Edition","pixels":208880,"type":"image\/png"}],"twitter_card":"summary","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/luxwatch.it\/orologi\/#website","url":"https:\/\/luxwatch.it\/orologi\/","name":"Luxwatch.it","description":"orologi di lusso","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/luxwatch.it\/orologi\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"ImageObject","@id":"https:\/\/luxwatch.it\/orologi\/franck-muller\/franck-muller-cintr-7500scatdtfocolcrdltd5n-blc\/#primaryimage","inLanguage":"it-IT","url":"https:\/\/luxwatch.it\/orologi\/wp-content\/uploads\/2019\/02\/7500SCATDTFOCOLCRDLTD5N-BLC-Franck-Muller-Cintr.png","contentUrl":"https:\/\/luxwatch.it\/orologi\/wp-content\/uploads\/2019\/02\/7500SCATDTFOCOLCRDLTD5N-BLC-Franck-Muller-Cintr.png","width":373,"height":560,"caption":"7500SCATDTFOCOLCRDLTD5N-BLC Franck Muller Cintr Swiss Lim. Edition"},{"@type":"WebPage","@id":"https:\/\/luxwatch.it\/orologi\/franck-muller\/franck-muller-cintr-7500scatdtfocolcrdltd5n-blc\/#webpage","url":"https:\/\/luxwatch.it\/orologi\/franck-muller\/franck-muller-cintr-7500scatdtfocolcrdltd5n-blc\/","name":"Franck Muller Cintr\u00e9e Curvex Swiss Lim. Edition 7500SCATDTFOCOLCRDLTD5N-BLC Oro rosa Acquisto Prezzo Migliore - Luxwatch.it","isPartOf":{"@id":"https:\/\/luxwatch.it\/orologi\/#website"},"primaryImageOfPage":{"@id":"https:\/\/luxwatch.it\/orologi\/franck-muller\/franck-muller-cintr-7500scatdtfocolcrdltd5n-blc\/#primaryimage"},"datePublished":"2019-02-20T12:46:55+00:00","dateModified":"2023-11-10T10:29:05+00:00","description":"Scopri l'orologio Franck Muller Cintr\u00e9e Curvex Swiss Lim. Edition 7500SCATDTFOCOLCRDLTD5N-BLC, con scheda dettagliata, prezzo e dove acquistarlo a un prezzo speciale.","breadcrumb":{"@id":"https:\/\/luxwatch.it\/orologi\/franck-muller\/franck-muller-cintr-7500scatdtfocolcrdltd5n-blc\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/luxwatch.it\/orologi\/franck-muller\/franck-muller-cintr-7500scatdtfocolcrdltd5n-blc\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/luxwatch.it\/orologi\/franck-muller\/franck-muller-cintr-7500scatdtfocolcrdltd5n-blc\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/luxwatch.it\/orologi\/"},{"@type":"ListItem","position":2,"name":"Trova il tuo orologio preferito al miglior prezzo.","item":"https:\/\/luxwatch.it\/orologi\/"},{"@type":"ListItem","position":3,"name":"Franck Muller Cintr\u00e9e Curvex Swiss Lim. Edition"}]}]}},"_links":{"self":[{"href":"https:\/\/luxwatch.it\/orologi\/wp-json\/wp\/v2\/product\/13212"}],"collection":[{"href":"https:\/\/luxwatch.it\/orologi\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/luxwatch.it\/orologi\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/luxwatch.it\/orologi\/wp-json\/wp\/v2\/media\/14023"}],"wp:attachment":[{"href":"https:\/\/luxwatch.it\/orologi\/wp-json\/wp\/v2\/media?parent=13212"}],"wp:term":[{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/luxwatch.it\/orologi\/wp-json\/wp\/v2\/product_cat?post=13212"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/luxwatch.it\/orologi\/wp-json\/wp\/v2\/product_tag?post=13212"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}