{"id":1029,"count":7,"description":"","link":"https:\/\/luxwatch.it\/orologi\/marche\/girard-perregaux\/cats-eye\/","name":"Cat`s Eye","slug":"cats-eye","taxonomy":"product_cat","parent":724,"meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v16.8 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Acquista Cat`s Eye Orologi al Miglior Prezzo - Luxwatch.it<\/title>\n<meta name=\"description\" content=\"Visualizza il catalogo con i Migliori orologi Cat`s Eye uomo o donna, con caratteristiche dettagliate, prezzo e con possibilit\u00e0 di acquisto Online.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/luxwatch.it\/orologi\/marche\/girard-perregaux\/cats-eye\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Acquista Cat`s Eye Orologi al Miglior Prezzo - Luxwatch.it\" \/>\n<meta property=\"og:description\" content=\"Visualizza il catalogo con i Migliori orologi Cat`s Eye uomo o donna, con caratteristiche dettagliate, prezzo e con possibilit\u00e0 di acquisto Online.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/luxwatch.it\/orologi\/marche\/girard-perregaux\/cats-eye\/\" \/>\n<meta property=\"og:site_name\" content=\"Luxwatch.it\" \/>\n<meta name=\"twitter:card\" content=\"summary\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/luxwatch.it\/orologi\/#website\",\"url\":\"https:\/\/luxwatch.it\/orologi\/\",\"name\":\"Luxwatch.it\",\"description\":\"orologi di lusso\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/luxwatch.it\/orologi\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"it-IT\"},{\"@type\":\"CollectionPage\",\"@id\":\"https:\/\/luxwatch.it\/orologi\/marche\/girard-perregaux\/cats-eye\/#webpage\",\"url\":\"https:\/\/luxwatch.it\/orologi\/marche\/girard-perregaux\/cats-eye\/\",\"name\":\"Acquista Cat`s Eye Orologi al Miglior Prezzo - Luxwatch.it\",\"isPartOf\":{\"@id\":\"https:\/\/luxwatch.it\/orologi\/#website\"},\"description\":\"Visualizza il catalogo con i Migliori orologi Cat`s Eye uomo o donna, con caratteristiche dettagliate, prezzo e con possibilit\\u00e0 di acquisto Online.\",\"breadcrumb\":{\"@id\":\"https:\/\/luxwatch.it\/orologi\/marche\/girard-perregaux\/cats-eye\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/luxwatch.it\/orologi\/marche\/girard-perregaux\/cats-eye\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/luxwatch.it\/orologi\/marche\/girard-perregaux\/cats-eye\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/luxwatch.it\/orologi\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Girard Perregaux\",\"item\":\"https:\/\/luxwatch.it\/orologi\/marche\/girard-perregaux\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Cat`s Eye\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Acquista Cat`s Eye Orologi al Miglior Prezzo - Luxwatch.it","description":"Visualizza il catalogo con i Migliori orologi Cat`s Eye uomo o donna, con caratteristiche dettagliate, prezzo e con possibilit\u00e0 di acquisto Online.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/luxwatch.it\/orologi\/marche\/girard-perregaux\/cats-eye\/","og_locale":"it_IT","og_type":"article","og_title":"Acquista Cat`s Eye Orologi al Miglior Prezzo - Luxwatch.it","og_description":"Visualizza il catalogo con i Migliori orologi Cat`s Eye uomo o donna, con caratteristiche dettagliate, prezzo e con possibilit\u00e0 di acquisto Online.","og_url":"https:\/\/luxwatch.it\/orologi\/marche\/girard-perregaux\/cats-eye\/","og_site_name":"Luxwatch.it","twitter_card":"summary","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"https:\/\/luxwatch.it\/orologi\/#website","url":"https:\/\/luxwatch.it\/orologi\/","name":"Luxwatch.it","description":"orologi di lusso","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/luxwatch.it\/orologi\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"it-IT"},{"@type":"CollectionPage","@id":"https:\/\/luxwatch.it\/orologi\/marche\/girard-perregaux\/cats-eye\/#webpage","url":"https:\/\/luxwatch.it\/orologi\/marche\/girard-perregaux\/cats-eye\/","name":"Acquista Cat`s Eye Orologi al Miglior Prezzo - Luxwatch.it","isPartOf":{"@id":"https:\/\/luxwatch.it\/orologi\/#website"},"description":"Visualizza il catalogo con i Migliori orologi Cat`s Eye uomo o donna, con caratteristiche dettagliate, prezzo e con possibilit\u00e0 di acquisto Online.","breadcrumb":{"@id":"https:\/\/luxwatch.it\/orologi\/marche\/girard-perregaux\/cats-eye\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/luxwatch.it\/orologi\/marche\/girard-perregaux\/cats-eye\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/luxwatch.it\/orologi\/marche\/girard-perregaux\/cats-eye\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/luxwatch.it\/orologi\/"},{"@type":"ListItem","position":2,"name":"Girard Perregaux","item":"https:\/\/luxwatch.it\/orologi\/marche\/girard-perregaux\/"},{"@type":"ListItem","position":3,"name":"Cat`s Eye"}]}]}},"_links":{"self":[{"href":"https:\/\/luxwatch.it\/orologi\/wp-json\/wp\/v2\/product_cat\/1029"}],"collection":[{"href":"https:\/\/luxwatch.it\/orologi\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/luxwatch.it\/orologi\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/luxwatch.it\/orologi\/wp-json\/wp\/v2\/product_cat\/724"}],"wp:post_type":[{"href":"https:\/\/luxwatch.it\/orologi\/wp-json\/wp\/v2\/product?product_cat=1029"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}